{"id":2103,"date":"2022-03-18T17:46:37","date_gmt":"2022-03-18T16:46:37","guid":{"rendered":"https:\/\/adventureinserbia.com\/?page_id=2103"},"modified":"2022-05-09T18:14:47","modified_gmt":"2022-05-09T16:14:47","slug":"istorija-i-naslede","status":"publish","type":"page","link":"https:\/\/adventureinserbia.com\/en\/dozivi\/istorija-i-naslede\/","title":{"rendered":"History and Heritage"},"content":{"rendered":"<div class=\"nicepage-container\"><div class=\"\" style=\"\" >        <script>\n            (function ($) {\n                var ResponsiveCms = window.ResponsiveCms;\n                if (!ResponsiveCms) {\n                    return;\n                }\n                ResponsiveCms.contentDom = $('script:last').parent();\n                ResponsiveCms.prevMode = \"XL\";\n\n                if (typeof ResponsiveCms.recalcClasses === 'function') {\n                    ResponsiveCms.recalcClasses();\n                }\n            })(jQuery);\n        <\/script>\n        \n    \n    <section class=\"u-align-right u-clearfix u-image u-section-2\" src=\"\" id=\"sec-efdd\" data-image-width=\"1920\" data-image-height=\"1440\" style=\"background-image: url(&quot;https:\/\/adventureinserbia.com\/wp-content\/uploads\/2022\/04\/belgrade-g8311074a9_1920.jpg&quot;);\">\n      <div class=\"u-clearfix u-sheet u-valign-middle u-sheet-1\">\n        <div class=\"u-container-style u-expanded-width-xs u-group u-shape-rectangle u-group-1\" data-animation-name=\"customAnimationIn\" data-animation-duration=\"1000\" data-animation-out=\"0\">\n          <div class=\"u-container-layout u-container-layout-1\">\n            <h1 class=\"u-align-right u-text u-text-body-alt-color u-title u-text-1\">Istorija i kulturno nasle\u0111e<\/h1>\n          <\/div>\n        <\/div>\n        <p class=\"u-large-text u-text u-text-body-alt-color u-text-variant u-text-2\" data-animation-name=\"customAnimationIn\" data-animation-duration=\"1000\" data-animation-delay=\"250\" data-animation-out=\"0\">Pro\u0111ite kroz vi\u0161e od 8000 godina istorije.<\/p>\n        <a href=\"#\" class=\"u-border-none u-btn u-btn-round u-button-style u-custom-color-6 u-radius-50 u-btn-1\" data-animation-name=\"customAnimationIn\" data-animation-duration=\"1000\" data-animation-delay=\"250\" data-animation-out=\"0\">Vi\u0161e<\/a>\n      <\/div>\n    <\/section>\n    <section class=\"skrollable u-clearfix u-section-3\" id=\"sec-47c9\">\n      <div class=\"u-clearfix u-sheet u-sheet-1\">\n        <div class=\"u-align-center u-container-style u-expanded-width-sm u-expanded-width-xs u-group u-group-1\">\n          <div class=\"u-container-layout u-valign-middle-md u-valign-middle-sm u-valign-middle-xl u-container-layout-1\">\n            <h2 class=\"u-text u-text-palette-1-base u-text-1\">Vekovima stara istorija i nasle\u0111e<\/h2>\n            <p class=\"u-text u-text-palette-1-dark-1 u-text-2\">Od drevnih civilizacija do moderne Srbije!<\/p>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/section>\n    <section class=\"u-clearfix u-gradient u-section-4\" id=\"sec-44d3\">\n      <div class=\"u-clearfix u-sheet u-sheet-1\">\n        <div class=\"u-align-center-md u-align-center-sm u-align-center-xs u-clearfix u-disable-padding u-expanded-width-sm u-gutter-10 u-layout-wrap u-layout-wrap-1\">\n          <div class=\"u-layout\">\n            <div class=\"u-layout-row\">\n              <div class=\"u-align-center-sm u-align-center-xl u-align-center-xs u-container-style u-layout-cell u-left-cell u-opacity u-opacity-25 u-similar-fill u-size-15 u-size-30-md u-white u-layout-cell-1\" data-animation-name=\"customAnimationIn\" data-animation-duration=\"1000\" data-animation-out=\"0\">\n                <div class=\"u-container-layout u-valign-middle u-container-layout-1\"><span class=\"u-file-icon u-icon u-icon-1\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/adventureinserbia.com\/wp-content\/uploads\/2022\/05\/1888578.png?w=1300&#038;ssl=1\" alt=\"\"><\/span>\n                  <h3 class=\"u-align-center-lg u-align-center-md u-text u-text-1\">Praistorija<\/h3>\n                  <div class=\"u-border-2 u-border-palette-1-base u-line u-line-horizontal u-line-1\"><\/div>\n                  <p class=\"u-align-center-lg u-align-center-md u-text u-text-font u-text-2\">Putovanje kroz vekove i drevne civilizacije. Istra\u017eite pro\u0161le vekove.<\/p>\n                  <a href=\"#\" class=\"u-active-none u-align-center-xs u-border-2 u-border-palette-1-base u-bottom-left-radius-0 u-bottom-right-radius-0 u-btn u-btn-rectangle u-button-style u-hover-none u-none u-radius-0 u-top-left-radius-0 u-top-right-radius-0 u-btn-1\">Vi\u0161e<\/a>\n                <\/div>\n              <\/div>\n              <div class=\"u-align-center-md u-align-center-sm u-align-center-xl u-align-center-xs u-container-style u-layout-cell u-opacity u-opacity-25 u-similar-fill u-size-15 u-size-30-md u-white u-layout-cell-2\" data-animation-name=\"customAnimationIn\" data-animation-duration=\"1000\" data-animation-delay=\"250\" data-animation-out=\"0\">\n                <div class=\"u-container-layout u-valign-middle u-container-layout-2\"><span class=\"u-align-center-xs u-file-icon u-icon u-icon-2\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/adventureinserbia.com\/wp-content\/uploads\/2022\/05\/2720255.png?w=1300&#038;ssl=1\" alt=\"\"><\/span>\n                  <h3 class=\"u-align-center-lg u-text u-text-3\">Rimsko Carstvo<\/h3>\n                  <div class=\"u-border-2 u-border-palette-1-base u-line u-line-horizontal u-line-2\"><\/div>\n                  <p class=\"u-align-center-lg u-text u-text-font u-text-4\">Putevima rimskih careva. Od severa pa sve do krajnjeg juga Srbije.<\/p>\n                  <a href=\"#\" class=\"u-active-none u-align-center u-border-2 u-border-palette-1-base u-bottom-left-radius-0 u-bottom-right-radius-0 u-btn u-btn-rectangle u-button-style u-hover-none u-none u-radius-0 u-top-left-radius-0 u-top-right-radius-0 u-btn-2\"> Vi\u0161e<\/a>\n                <\/div>\n              <\/div>\n              <div class=\"u-align-center-lg u-align-center-md u-align-center-sm u-align-center-xs u-container-style u-layout-cell u-opacity u-opacity-25 u-similar-fill u-size-15 u-size-30-md u-white u-layout-cell-3\" data-animation-name=\"customAnimationIn\" data-animation-duration=\"1000\" data-animation-delay=\"500\" data-animation-out=\"0\">\n                <div class=\"u-container-layout u-valign-middle u-container-layout-3\"><span class=\"u-file-icon u-icon u-icon-3\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/adventureinserbia.com\/wp-content\/uploads\/2022\/05\/618855.png?w=1300&#038;ssl=1\" alt=\"\"><\/span>\n                  <h3 class=\"u-align-center u-text u-text-5\">Srednji Vek<\/h3>\n                  <div class=\"u-border-2 u-border-palette-1-base u-line u-line-horizontal u-line-3\"><\/div>\n                  <p class=\"u-align-center-xl u-text u-text-font u-text-6\">Istra\u017eite sve o Srbiji u srednjem veku i velikom kulturnom nasle\u0111u.<\/p>\n                  <a href=\"#\" class=\"u-active-none u-align-center-md u-align-center-sm u-align-center-xs u-border-2 u-border-palette-1-base u-bottom-left-radius-0 u-bottom-right-radius-0 u-btn u-btn-rectangle u-button-style u-hover-none u-none u-radius-0 u-top-left-radius-0 u-top-right-radius-0 u-btn-3\"> Vi\u0161e<\/a>\n                <\/div>\n              <\/div>\n              <div class=\"u-align-center-md u-align-center-sm u-align-center-xl u-align-center-xs u-container-style u-layout-cell u-opacity u-opacity-25 u-right-cell u-similar-fill u-size-15 u-size-30-md u-white u-layout-cell-4\" data-animation-name=\"customAnimationIn\" data-animation-duration=\"1000\" data-animation-delay=\"750\" data-animation-out=\"0\">\n                <div class=\"u-container-layout u-valign-middle u-container-layout-4\"><span class=\"u-file-icon u-icon u-icon-4\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/adventureinserbia.com\/wp-content\/uploads\/2022\/05\/1046325.png?w=1300&#038;ssl=1\" alt=\"\"><\/span>\n                  <h3 class=\"u-align-center-lg u-text u-text-7\">Moderno Doba<\/h3>\n                  <div class=\"u-border-2 u-border-palette-1-base u-line u-line-horizontal u-line-4\"><\/div>\n                  <p class=\"u-align-center-lg u-text u-text-font u-text-8\">Mesta od izuzetnog istorijskog zna\u010daja za modernu Srbiju.<\/p>\n                  <a href=\"#\" class=\"u-active-none u-align-center-md u-align-center-sm u-align-center-xs u-border-2 u-border-palette-1-base u-bottom-left-radius-0 u-bottom-right-radius-0 u-btn u-btn-rectangle u-button-style u-hover-none u-none u-radius-0 u-top-left-radius-0 u-top-right-radius-0 u-btn-4\"> Vi\u0161e<\/a>\n                <\/div>\n              <\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/section>\n    <section class=\"skrollable u-align-left u-clearfix u-section-5\" id=\"sec-ca61\">\n      <div class=\"u-align-left u-clearfix u-sheet u-sheet-1\">\n        <h1 class=\"u-align-center-md u-align-center-sm u-align-center-xs u-text u-text-default-lg u-text-default-xl u-text-1\"> Popularne ponude, ba\u0161 sad.<\/h1>\n        <div class=\"u-expanded-width-xs u-shortcode u-shortcode-1\"><\/div>\n      <\/div>\n    <\/section>\n    <section class=\"skrollable u-clearfix u-palette-1-base u-section-6\" id=\"sec-0cda\">\n      <div class=\"u-clearfix u-sheet u-valign-middle u-sheet-1\">\n        <div class=\"u-align-center u-container-style u-expanded-width-sm u-expanded-width-xs u-group u-group-1\">\n          <div class=\"u-container-layout u-valign-middle-md u-valign-middle-sm u-valign-middle-xl u-container-layout-1\">\n            <h2 class=\"u-align-center u-text u-text-1\">Dodajte na svoju rutu odmah<\/h2>\n            <p class=\"u-align-center u-text u-text-2\">Istorijska mesta koja trebate posetiti u Srbiji.<\/p>\n          <\/div>\n        <\/div>\n        <a href=\"#\" class=\"u-align-center-lg u-align-center-md u-align-center-sm u-align-center-xs u-border-none u-btn u-btn-round u-button-style u-custom-color-6 u-radius-50 u-btn-1\">Vi\u0161e<\/a>\n      <\/div>\n    <\/section>\n    <section class=\"skrollable u-border-1 u-border-custom-color-4 u-border-no-left u-border-no-right u-border-no-top u-clearfix u-gradient u-valign-middle u-section-7\" id=\"sec-0db9\">\n      <div class=\"u-align-center u-clearfix u-gutter-10 u-layout-wrap u-layout-wrap-1\">\n        <div class=\"u-layout\">\n          <div class=\"u-layout-row\">\n            <div class=\"u-container-style u-layout-cell u-size-30 u-layout-cell-1\">\n              <div class=\"u-container-layout u-container-layout-1\">\n                <div class=\"u-container-style u-expanded-width u-group u-similar-fill u-group-1\">\n                  <div class=\"u-container-layout u-container-layout-2\">\n                    <h2 class=\"u-align-center u-custom-font u-text u-text-palette-1-base u-text-1\"> Pratite nas na mre\u017eama<\/h2>\n                    <div class=\"u-border-2 u-border-palette-1-base u-line u-line-horizontal u-line-1\"><\/div>\n                    <p class=\"u-align-center u-text u-text-font u-text-2\"> Inspiri\u0161ite se za novu avanturu!<\/p>\n                    <div class=\"u-social-icons u-spacing-20 u-social-icons-1\">\n                      <a class=\"u-social-url\" title=\"facebook\" target=\"_blank\" href=\"https:\/\/facebook.com\/name\"><span class=\"u-icon u-social-facebook u-social-icon u-text-custom-color-5\"><svg class=\"u-svg-link\" preserveAspectRatio=\"xMidYMin slice\" viewBox=\"0 0 512 512\" style=\"\"><use xlink:href=\"#svg-5e9f\"><\/use><\/svg><svg class=\"u-svg-content\" viewBox=\"0 0 512 512\" id=\"svg-5e9f\"><path d=\"m512 256c0-141.4-114.6-256-256-256s-256 114.6-256 256 114.6 256 256 256c1.5 0 3 0 4.5-.1v-199.2h-55v-64.1h55v-47.2c0-54.7 33.4-84.5 82.2-84.5 23.4 0 43.5 1.7 49.3 2.5v57.2h-33.6c-26.5 0-31.7 12.6-31.7 31.1v40.8h63.5l-8.3 64.1h-55.2v189.5c107-30.7 185.3-129.2 185.3-246.1z\"><\/path><\/svg><\/span>\n                      <\/a>\n                      <a class=\"u-social-url\" title=\"instagram\" target=\"_blank\" href=\"https:\/\/instagram.com\/name\"><span class=\"u-icon u-social-icon u-social-instagram u-text-custom-color-5\"><svg class=\"u-svg-link\" preserveAspectRatio=\"xMidYMin slice\" viewBox=\"0 0 512 512\" style=\"\"><use xlink:href=\"#svg-ddc9\"><\/use><\/svg><svg class=\"u-svg-content\" viewBox=\"0 0 512 512\" id=\"svg-ddc9\"><path d=\"m305 256c0 27.0625-21.9375 49-49 49s-49-21.9375-49-49 21.9375-49 49-49 49 21.9375 49 49zm0 0\"><\/path><path d=\"m370.59375 169.304688c-2.355469-6.382813-6.113281-12.160157-10.996094-16.902344-4.742187-4.882813-10.515625-8.640625-16.902344-10.996094-5.179687-2.011719-12.960937-4.40625-27.292968-5.058594-15.503906-.707031-20.152344-.859375-59.402344-.859375-39.253906 0-43.902344.148438-59.402344.855469-14.332031.65625-22.117187 3.050781-27.292968 5.0625-6.386719 2.355469-12.164063 6.113281-16.902344 10.996094-4.882813 4.742187-8.640625 10.515625-11 16.902344-2.011719 5.179687-4.40625 12.964843-5.058594 27.296874-.707031 15.5-.859375 20.148438-.859375 59.402344 0 39.25.152344 43.898438.859375 59.402344.652344 14.332031 3.046875 22.113281 5.058594 27.292969 2.359375 6.386719 6.113281 12.160156 10.996094 16.902343 4.742187 4.882813 10.515624 8.640626 16.902343 10.996094 5.179688 2.015625 12.964844 4.410156 27.296875 5.0625 15.5.707032 20.144532.855469 59.398438.855469 39.257812 0 43.90625-.148437 59.402344-.855469 14.332031-.652344 22.117187-3.046875 27.296874-5.0625 12.820313-4.945312 22.953126-15.078125 27.898438-27.898437 2.011719-5.179688 4.40625-12.960938 5.0625-27.292969.707031-15.503906.855469-20.152344.855469-59.402344 0-39.253906-.148438-43.902344-.855469-59.402344-.652344-14.332031-3.046875-22.117187-5.0625-27.296874zm-114.59375 162.179687c-41.691406 0-75.488281-33.792969-75.488281-75.484375s33.796875-75.484375 75.488281-75.484375c41.6875 0 75.484375 33.792969 75.484375 75.484375s-33.796875 75.484375-75.484375 75.484375zm78.46875-136.3125c-9.742188 0-17.640625-7.898437-17.640625-17.640625s7.898437-17.640625 17.640625-17.640625 17.640625 7.898437 17.640625 17.640625c-.003906 9.742188-7.898437 17.640625-17.640625 17.640625zm0 0\"><\/path><path d=\"m256 0c-141.363281 0-256 114.636719-256 256s114.636719 256 256 256 256-114.636719 256-256-114.636719-256-256-256zm146.113281 316.605469c-.710937 15.648437-3.199219 26.332031-6.832031 35.683593-7.636719 19.746094-23.246094 35.355469-42.992188 42.992188-9.347656 3.632812-20.035156 6.117188-35.679687 6.832031-15.675781.714844-20.683594.886719-60.605469.886719-39.925781 0-44.929687-.171875-60.609375-.886719-15.644531-.714843-26.332031-3.199219-35.679687-6.832031-9.8125-3.691406-18.695313-9.476562-26.039063-16.957031-7.476562-7.339844-13.261719-16.226563-16.953125-26.035157-3.632812-9.347656-6.121094-20.035156-6.832031-35.679687-.722656-15.679687-.890625-20.6875-.890625-60.609375s.167969-44.929688.886719-60.605469c.710937-15.648437 3.195312-26.332031 6.828125-35.683593 3.691406-9.808594 9.480468-18.695313 16.960937-26.035157 7.339844-7.480469 16.226563-13.265625 26.035157-16.957031 9.351562-3.632812 20.035156-6.117188 35.683593-6.832031 15.675781-.714844 20.683594-.886719 60.605469-.886719s44.929688.171875 60.605469.890625c15.648437.710937 26.332031 3.195313 35.683593 6.824219 9.808594 3.691406 18.695313 9.480468 26.039063 16.960937 7.476563 7.34375 13.265625 16.226563 16.953125 26.035157 3.636719 9.351562 6.121094 20.035156 6.835938 35.683593.714843 15.675781.882812 20.683594.882812 60.605469s-.167969 44.929688-.886719 60.605469zm0 0\"><\/path><\/svg><\/span>\n                      <\/a>\n                      <a class=\"u-social-url\" target=\"_blank\" data-type=\"Custom\" title=\"pinterest\" href=\"https:\/\/pinterest.com\/name\"><span class=\"u-icon u-social-custom u-social-icon u-text-custom-color-5 u-icon-3\"><svg class=\"u-svg-link\" preserveAspectRatio=\"xMidYMin slice\" viewBox=\"0 0 97.75 97.75\" style=\"\"><use xlink:href=\"#svg-251c\"><\/use><\/svg><svg class=\"u-svg-content\" viewBox=\"0 0 97.75 97.75\" x=\"0px\" y=\"0px\" id=\"svg-251c\" style=\"enable-background:new 0 0 97.75 97.75;\"><g><path d=\"M48.875,0C21.883,0,0,21.882,0,48.875S21.883,97.75,48.875,97.75S97.75,75.868,97.75,48.875S75.867,0,48.875,0z    M54.499,65.109c-4.521,0-8.773-2.444-10.229-5.219c0,0-2.432,9.645-2.943,11.506c-1.813,6.58-7.146,13.162-7.561,13.701   c-0.289,0.375-0.928,0.258-0.994-0.24c-0.113-0.838-1.475-9.139,0.127-15.909c0.801-3.4,5.383-22.814,5.383-22.814   s-1.334-2.673-1.334-6.625c0-6.205,3.596-10.837,8.074-10.837c3.807,0,5.645,2.859,5.645,6.286c0,3.828-2.436,9.552-3.693,14.856   c-1.051,4.441,2.225,8.064,6.605,8.064c7.933,0,13.272-10.188,13.272-22.261c0-9.174-6.176-16.044-17.418-16.044   c-12.697,0-20.615,9.471-20.615,20.052c0,3.646,1.078,6.221,2.764,8.21c0.773,0.915,0.883,1.283,0.602,2.333   c-0.203,0.771-0.66,2.625-0.854,3.358c-0.279,1.062-1.137,1.44-2.098,1.049c-5.846-2.387-8.572-8.793-8.572-15.994   c0-11.893,10.029-26.154,29.922-26.154c15.985,0,26.506,11.566,26.506,23.984C77.089,52.839,67.956,65.109,54.499,65.109z\"><\/path>\n<\/g><\/svg><\/span>\n                      <\/a>\n                    <\/div>\n                  <\/div>\n                <\/div>\n              <\/div>\n            <\/div>\n            <div class=\"u-container-style u-layout-cell u-size-30 u-layout-cell-2\">\n              <div class=\"u-container-layout u-container-layout-3\">\n                <div class=\"u-align-center-sm u-container-style u-expanded-width u-group u-similar-fill u-group-2\">\n                  <div class=\"u-container-layout u-container-layout-4\">\n                    <h2 class=\"u-align-center-lg u-align-center-md u-align-center-xl u-align-center-xs u-text u-text-palette-1-base u-text-3\"> Prijavite se na newsletter<\/h2>\n                    <div class=\"u-border-2 u-border-palette-1-base u-line u-line-horizontal u-line-2\"><\/div>\n                    <p class=\"u-align-center-lg u-align-center-md u-align-center-xl u-align-center-xs u-text u-text-font u-text-4\"> Prijavite se na newsletter i primajte najnovije vesti i specijalne popuste!<\/p>\n                  <\/div>\n                <\/div>\n                <div class=\"u-shortcode u-shortcode-1\">\n\t\t\t<form id=\"sib_signup_form_2\" method=\"post\" class=\"sib_signup_form\">\n\t\t\t\t<div class=\"sib_loader\" style=\"display:none;\"><img data-recalc-dims=\"1\"\n\t\t\t\t\t\t\tsrc=\"https:\/\/i0.wp.com\/adventureinserbia.com\/wp-includes\/images\/spinner.gif?w=1300&#038;ssl=1\" alt=\"loader\"><\/div>\n\t\t\t\t<input type=\"hidden\" name=\"sib_form_action\" value=\"subscribe_form_submit\">\n\t\t\t\t<input type=\"hidden\" name=\"sib_form_id\" value=\"2\">\n                <input type=\"hidden\" name=\"sib_form_alert_notice\" value=\"Molim vas popunite ovo polje.\">\n                <input type=\"hidden\" name=\"sib_form_invalid_email_notice\" value=\"Va\u0161a adresa e-po\u0161te je neva\u017eec\u0301a.\">\n                <input type=\"hidden\" name=\"sib_security\" value=\"0b13d005ac\">\n\t\t\t\t<div class=\"sib_signup_box_inside_2\">\n\t\t\t\t\t<div style=\"\/*display:none*\/\" class=\"sib_msg_disp\">\n\t\t\t\t\t<\/div>\n                    \t\t\t\t\t<p class=\"sib-email-area\">\r\n    <label class=\"sib-email-area\">Adresa e-po\u0161te*<\/label>\r\n    <input type=\"email\" class=\"sib-email-area\" name=\"email\" required=\"required\">\r\n<\/p>\r\n<p class=\"sib-FIRSTNAME-area\">\r\n    <label class=\"sib-NAME-area\">Ime*<\/label>\r\n    <input type=\"text\" class=\"sib-FIRSTNAME-area\" name=\"FIRSTNAME\" required=\"required\">\r\n<\/p>\r\n<p>\r\n<input type=\"checkbox\" name=\"terms\" required=\"required\">Prihvatam politiku privatnosti i saglasan\/a sam da primam e-po\u0161tu.<\/a>\r\n<\/p>\r\n<p>\r\n    <input type=\"submit\" class=\"sib-default-btn\" value=\"Prijavi se\">\r\n<\/p>\t\t\t\t<\/div>\n\t\t\t<\/form>\n\t\t\t<style>\n\t\t\t\tform#sib_signup_form_2 { padding: 0px; -moz-box-sizing:border-box; -webkit-box-sizing: border-box; box-sizing: border-box; } form#sib_signup_form_2 input[type=text],form#sib_signup_form_2 input[type=email], form#sib_signup_form_2 select { width: 95%; border: 1px solid #bbb; height: 35px; margin: 5px 0 0 0; } form#sib_signup_form_2 .sib-default-btn {width: 50%; height: 50px; margin: 5px 0; padding: 6px 12px; color:#ffffff; background-color: #C7363D; border-color: #C7363D; font-size: 18px; font-weight:400; line-height: 1.4285; text-align: center; cursor: pointer; vertical-align: middle; -webkit-user-select:none; -moz-user-select:none; -ms-user-select:none; user-select:none; white-space: normal; border:1px solid transparent; border-radius: 25px; } form#sib_signup_form_2 .sib-default-btn:hover {background-color: #C7363D; } form#sib_signup_form_2 p{ margin: 10px 0 0 0; }form#sib_signup_form_2 p.sib-alert-message {\n    padding: 6px 12px;\n    margin-bottom: 20px;\n    border: 1px solid transparent;\n    border-radius: 4px;\n    -webkit-box-sizing: border-box;\n    -moz-box-sizing: border-box;\n    box-sizing: border-box;\n}\nform#sib_signup_form_2 p.sib-alert-message-error {\n    background-color: #f2dede;\n    border-color: #ebccd1;\n    color: #a94442;\n}\nform#sib_signup_form_2 p.sib-alert-message-success {\n    background-color: #dff0d8;\n    border-color: #d6e9c6;\n    color: #3c763d;\n}\nform#sib_signup_form_2 p.sib-alert-message-warning {\n    background-color: #fcf8e3;\n    border-color: #faebcc;\n    color: #8a6d3b;\n}\n\t\t\t<\/style>\n\t\t\t<\/div>\n              <\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/section>\n    \n    \n  \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Istorija i kulturno nasle\u0111e Pro\u0111ite kroz vi\u0161e od 8000 godina istorije. Vi\u0161e Vekovima stara istorija i nasle\u0111e Od drevnih civilizacija do moderne Srbije! Praistorija Putovanje kroz vekove i drevne civilizacije. Istra\u017eite pro\u0161le vekove. Vi\u0161e Rimsko Carstvo Putevima rimskih careva. Od severa pa sve do krajnjeg juga Srbije. Vi\u0161e Srednji Vek Istra\u017eite sve o Srbiji u [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":43,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"qi-full-width.php","meta":{"_uag_custom_page_level_css":"","footnotes":""},"class_list":["post-2103","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Istorija i Nasle\u0111e - Adventure in Serbia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adventureinserbia.com\/en\/dozivi\/istorija-i-naslede\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Istorija i Nasle\u0111e - Adventure in Serbia\" \/>\n<meta property=\"og:description\" content=\"Istorija i kulturno nasle\u0111e Pro\u0111ite kroz vi\u0161e od 8000 godina istorije. Vi\u0161e Vekovima stara istorija i nasle\u0111e Od drevnih civilizacija do moderne Srbije! Praistorija Putovanje kroz vekove i drevne civilizacije. Istra\u017eite pro\u0161le vekove. Vi\u0161e Rimsko Carstvo Putevima rimskih careva. Od severa pa sve do krajnjeg juga Srbije. Vi\u0161e Srednji Vek Istra\u017eite sve o Srbiji u [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adventureinserbia.com\/en\/dozivi\/istorija-i-naslede\/\" \/>\n<meta property=\"og:site_name\" content=\"Adventure in Serbia\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-09T16:14:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adventureinserbia.com\\\/dozivi\\\/istorija-i-naslede\\\/\",\"url\":\"https:\\\/\\\/adventureinserbia.com\\\/dozivi\\\/istorija-i-naslede\\\/\",\"name\":\"Istorija i Nasle\u0111e - Adventure in Serbia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adventureinserbia.com\\\/#website\"},\"datePublished\":\"2022-03-18T16:46:37+00:00\",\"dateModified\":\"2022-05-09T16:14:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adventureinserbia.com\\\/dozivi\\\/istorija-i-naslede\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adventureinserbia.com\\\/dozivi\\\/istorija-i-naslede\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adventureinserbia.com\\\/dozivi\\\/istorija-i-naslede\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Po\u010detna\",\"item\":\"https:\\\/\\\/adventureinserbia.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Do\u017eivi\",\"item\":\"https:\\\/\\\/adventureinserbia.com\\\/dozivi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Istorija i Nasle\u0111e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adventureinserbia.com\\\/#website\",\"url\":\"https:\\\/\\\/adventureinserbia.com\\\/\",\"name\":\"Adventure in Serbia\",\"description\":\"Come, See, Taste, Feel\",\"publisher\":{\"@id\":\"https:\\\/\\\/adventureinserbia.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adventureinserbia.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adventureinserbia.com\\\/#organization\",\"name\":\"Adventure in Serbia\",\"url\":\"https:\\\/\\\/adventureinserbia.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/adventureinserbia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/adventureinserbia.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/cropped-Logo2.png?fit=500%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/adventureinserbia.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/cropped-Logo2.png?fit=500%2C500&ssl=1\",\"width\":500,\"height\":500,\"caption\":\"Adventure in Serbia\"},\"image\":{\"@id\":\"https:\\\/\\\/adventureinserbia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Istorija i Nasle\u0111e - Adventure in Serbia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adventureinserbia.com\/en\/dozivi\/istorija-i-naslede\/","og_locale":"en_US","og_type":"article","og_title":"Istorija i Nasle\u0111e - Adventure in Serbia","og_description":"Istorija i kulturno nasle\u0111e Pro\u0111ite kroz vi\u0161e od 8000 godina istorije. Vi\u0161e Vekovima stara istorija i nasle\u0111e Od drevnih civilizacija do moderne Srbije! Praistorija Putovanje kroz vekove i drevne civilizacije. Istra\u017eite pro\u0161le vekove. Vi\u0161e Rimsko Carstvo Putevima rimskih careva. Od severa pa sve do krajnjeg juga Srbije. Vi\u0161e Srednji Vek Istra\u017eite sve o Srbiji u [&hellip;]","og_url":"https:\/\/adventureinserbia.com\/en\/dozivi\/istorija-i-naslede\/","og_site_name":"Adventure in Serbia","article_modified_time":"2022-05-09T16:14:47+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adventureinserbia.com\/dozivi\/istorija-i-naslede\/","url":"https:\/\/adventureinserbia.com\/dozivi\/istorija-i-naslede\/","name":"Istorija i Nasle\u0111e - Adventure in Serbia","isPartOf":{"@id":"https:\/\/adventureinserbia.com\/#website"},"datePublished":"2022-03-18T16:46:37+00:00","dateModified":"2022-05-09T16:14:47+00:00","breadcrumb":{"@id":"https:\/\/adventureinserbia.com\/dozivi\/istorija-i-naslede\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adventureinserbia.com\/dozivi\/istorija-i-naslede\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/adventureinserbia.com\/dozivi\/istorija-i-naslede\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Po\u010detna","item":"https:\/\/adventureinserbia.com\/"},{"@type":"ListItem","position":2,"name":"Do\u017eivi","item":"https:\/\/adventureinserbia.com\/dozivi\/"},{"@type":"ListItem","position":3,"name":"Istorija i Nasle\u0111e"}]},{"@type":"WebSite","@id":"https:\/\/adventureinserbia.com\/#website","url":"https:\/\/adventureinserbia.com\/","name":"Adventure in Serbia","description":"Come, See, Taste, Feel","publisher":{"@id":"https:\/\/adventureinserbia.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adventureinserbia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/adventureinserbia.com\/#organization","name":"Adventure in Serbia","url":"https:\/\/adventureinserbia.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/adventureinserbia.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/adventureinserbia.com\/wp-content\/uploads\/2022\/02\/cropped-Logo2.png?fit=500%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/adventureinserbia.com\/wp-content\/uploads\/2022\/02\/cropped-Logo2.png?fit=500%2C500&ssl=1","width":500,"height":500,"caption":"Adventure in Serbia"},"image":{"@id":"https:\/\/adventureinserbia.com\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"qode_essential_addons_image_size_square":false,"qode_essential_addons_image_size_landscape":false,"qode_essential_addons_image_size_portrait":false,"qode_essential_addons_image_size_huge-square":false},"uagb_author_info":{"display_name":"Joker","author_link":"https:\/\/adventureinserbia.com\/en\/author\/f-prime2442-ais\/"},"uagb_comment_info":0,"uagb_excerpt":"Istorija i kulturno nasle\u0111e Pro\u0111ite kroz vi\u0161e od 8000 godina istorije. Vi\u0161e Vekovima stara istorija i nasle\u0111e Od drevnih civilizacija do moderne Srbije! Praistorija Putovanje kroz vekove i drevne civilizacije. Istra\u017eite pro\u0161le vekove. Vi\u0161e Rimsko Carstvo Putevima rimskih careva. Od severa pa sve do krajnjeg juga Srbije. Vi\u0161e Srednji Vek Istra\u017eite sve o Srbiji u&hellip;","_links":{"self":[{"href":"https:\/\/adventureinserbia.com\/en\/wp-json\/wp\/v2\/pages\/2103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adventureinserbia.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/adventureinserbia.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/adventureinserbia.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adventureinserbia.com\/en\/wp-json\/wp\/v2\/comments?post=2103"}],"version-history":[{"count":5,"href":"https:\/\/adventureinserbia.com\/en\/wp-json\/wp\/v2\/pages\/2103\/revisions"}],"predecessor-version":[{"id":3310,"href":"https:\/\/adventureinserbia.com\/en\/wp-json\/wp\/v2\/pages\/2103\/revisions\/3310"}],"up":[{"embeddable":true,"href":"https:\/\/adventureinserbia.com\/en\/wp-json\/wp\/v2\/pages\/43"}],"wp:attachment":[{"href":"https:\/\/adventureinserbia.com\/en\/wp-json\/wp\/v2\/media?parent=2103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}